{"id":2730,"date":"2021-10-22T19:07:35","date_gmt":"2021-10-22T17:07:35","guid":{"rendered":"https:\/\/www.energeticambiente.it\/labenergie\/?page_id=2730"},"modified":"2021-12-03T08:46:25","modified_gmt":"2021-12-03T07:46:25","slug":"fonti-di-energia","status":"publish","type":"page","link":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/","title":{"rendered":"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><span style=\"color:#324b96\" class=\"has-inline-color\">Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"305\" height=\"140\" src=\"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/work-in-progress.jpg\" alt=\"\" class=\"wp-image-2769\" srcset=\"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/work-in-progress.jpg 305w, https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/work-in-progress-300x138.jpg 300w\" sizes=\"auto, (max-width: 305px) 100vw, 305px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#fffcda;flex-basis:33.33%\"><div class=\"menu-menu-educational-container\"><ul id=\"menu-menu-educational\" class=\"menu\"><li id=\"menu-item-2798\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2798\"><a href=\"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/\" data-ps2id-api=\"true\"><span class=\"menu-title\"><span class=\"menu-title-text\">Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili<\/span><\/span><\/a><\/li>\n<li id=\"menu-item-2919\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-2919\"><a href=\"https:\/\/www.energeticambiente.it\/labenergie\/pannello-solare-ad-aria\/\" data-ps2id-api=\"true\"><span class=\"menu-title\"><span class=\"menu-title-text\">Pannello solare ad aria<\/span><\/span><\/a><\/li>\n<\/ul><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"wp-block-paragraph\">In questa sezione del sito \u00e8 raccolta (e raccoglieremo) l&#8217;informazione scientifica su tutte le fonti energetiche e su tutte le tecnologie per la <strong>produzione di energia<\/strong>.<br>Cercheremo di riportare i dati pi\u00f9 solidi che si trovano in bibliografia ed estrapolati dalle fonti pi\u00f9 autorevoli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Attualmente la sezione \u00e8 in fase di sviluppo ma ogni settimana troverete qualcosa in pi\u00f9 fino a divenire un luogo di riferimento per le <strong>informazioni tecniche sulle Energie Rinnovabili<\/strong> e le <strong>fonti di energia primaria e secondaria<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per la navigazione in questa sezione basta fare riferimento al men\u00f9 di sinistra dove trovate tutte le<strong> fonti di energia<\/strong> inserite sino ad ora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Buona lettura e buono studio!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<ul class=\"wp-block-archives-list alignright wp-block-archives\">\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2026\/06\/'>Giugno 2026<\/a>&nbsp;(1)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2026\/04\/'>Aprile 2026<\/a>&nbsp;(3)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2026\/01\/'>Gennaio 2026<\/a>&nbsp;(1)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2025\/12\/'>Dicembre 2025<\/a>&nbsp;(4)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2025\/11\/'>Novembre 2025<\/a>&nbsp;(1)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2025\/10\/'>Ottobre 2025<\/a>&nbsp;(24)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2025\/09\/'>Settembre 2025<\/a>&nbsp;(45)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2025\/06\/'>Giugno 2025<\/a>&nbsp;(1)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2025\/04\/'>Aprile 2025<\/a>&nbsp;(1)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2025\/01\/'>Gennaio 2025<\/a>&nbsp;(2)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2024\/02\/'>Febbraio 2024<\/a>&nbsp;(1)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2022\/04\/'>Aprile 2022<\/a>&nbsp;(1)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2022\/02\/'>Febbraio 2022<\/a>&nbsp;(2)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2021\/12\/'>Dicembre 2021<\/a>&nbsp;(2)<\/li>\n\t<li><a href='https:\/\/www.energeticambiente.it\/labenergie\/2021\/10\/'>Ottobre 2021<\/a>&nbsp;(3)<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili In questa sezione del sito \u00e8 raccolta (e raccoglieremo) l&#8217;informazione scientifica su tutte le fonti energetiche e su tutte le tecnologie per la produzione di energia.Cercheremo di riportare i dati pi\u00f9 solidi che si trovano in bibliografia ed<span class=\"more-link\"><a href=\"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/\">Leggi tutto<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["entry","author-eroyka","post-2730","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili - Articoli - EnergeticAmbiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili - Articoli - EnergeticAmbiente\" \/>\n<meta property=\"og:description\" content=\"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili In questa sezione del sito \u00e8 raccolta (e raccoglieremo) l&#8217;informazione scientifica su tutte le fonti energetiche e su tutte le tecnologie per la produzione di energia.Cercheremo di riportare i dati pi\u00f9 solidi che si trovano in bibliografia edLeggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/\" \/>\n<meta property=\"og:site_name\" content=\"Articoli - EnergeticAmbiente\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-03T07:46:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/work-in-progress.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/fonti-di-energia\\\/\",\"url\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/fonti-di-energia\\\/\",\"name\":\"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili - Articoli - EnergeticAmbiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/fonti-di-energia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/fonti-di-energia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/work-in-progress.jpg\",\"datePublished\":\"2021-10-22T17:07:35+00:00\",\"dateModified\":\"2021-12-03T07:46:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/fonti-di-energia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/fonti-di-energia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/fonti-di-energia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/work-in-progress.jpg\",\"contentUrl\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/work-in-progress.jpg\",\"width\":305,\"height\":140},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/fonti-di-energia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/#website\",\"url\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/\",\"name\":\"LabEnergie\",\"description\":\"Le news della comunity EA\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/#\\\/schema\\\/person\\\/5e86256f3522d2465a9e3c7225fbcc0c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/#\\\/schema\\\/person\\\/5e86256f3522d2465a9e3c7225fbcc0c\",\"name\":\"energeticambiente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-labenergie-home.jpg\",\"url\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-labenergie-home.jpg\",\"contentUrl\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-labenergie-home.jpg\",\"width\":721,\"height\":121,\"caption\":\"energeticambiente\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.energeticambiente.it\\\/labenergie\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-labenergie-home.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili - Articoli - EnergeticAmbiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/","og_locale":"it_IT","og_type":"article","og_title":"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili - Articoli - EnergeticAmbiente","og_description":"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili In questa sezione del sito \u00e8 raccolta (e raccoglieremo) l&#8217;informazione scientifica su tutte le fonti energetiche e su tutte le tecnologie per la produzione di energia.Cercheremo di riportare i dati pi\u00f9 solidi che si trovano in bibliografia edLeggi tutto","og_url":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/","og_site_name":"Articoli - EnergeticAmbiente","article_modified_time":"2021-12-03T07:46:25+00:00","og_image":[{"url":"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/work-in-progress.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/","url":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/","name":"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili - Articoli - EnergeticAmbiente","isPartOf":{"@id":"https:\/\/www.energeticambiente.it\/labenergie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/#primaryimage"},"image":{"@id":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/work-in-progress.jpg","datePublished":"2021-10-22T17:07:35+00:00","dateModified":"2021-12-03T07:46:25+00:00","breadcrumb":{"@id":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/#primaryimage","url":"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/work-in-progress.jpg","contentUrl":"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/work-in-progress.jpg","width":305,"height":140},{"@type":"BreadcrumbList","@id":"https:\/\/www.energeticambiente.it\/labenergie\/fonti-di-energia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.energeticambiente.it\/labenergie\/"},{"@type":"ListItem","position":2,"name":"Cosa sono e quali sono le Fonti Energetiche Fossili e quelle Rinnovabili"}]},{"@type":"WebSite","@id":"https:\/\/www.energeticambiente.it\/labenergie\/#website","url":"https:\/\/www.energeticambiente.it\/labenergie\/","name":"LabEnergie","description":"Le news della comunity EA","publisher":{"@id":"https:\/\/www.energeticambiente.it\/labenergie\/#\/schema\/person\/5e86256f3522d2465a9e3c7225fbcc0c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.energeticambiente.it\/labenergie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.energeticambiente.it\/labenergie\/#\/schema\/person\/5e86256f3522d2465a9e3c7225fbcc0c","name":"energeticambiente","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/Logo-labenergie-home.jpg","url":"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/Logo-labenergie-home.jpg","contentUrl":"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/Logo-labenergie-home.jpg","width":721,"height":121,"caption":"energeticambiente"},"logo":{"@id":"https:\/\/www.energeticambiente.it\/labenergie\/wp-content\/uploads\/2021\/10\/Logo-labenergie-home.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.energeticambiente.it\/labenergie\/wp-json\/wp\/v2\/pages\/2730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.energeticambiente.it\/labenergie\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.energeticambiente.it\/labenergie\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.energeticambiente.it\/labenergie\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.energeticambiente.it\/labenergie\/wp-json\/wp\/v2\/comments?post=2730"}],"version-history":[{"count":16,"href":"https:\/\/www.energeticambiente.it\/labenergie\/wp-json\/wp\/v2\/pages\/2730\/revisions"}],"predecessor-version":[{"id":2921,"href":"https:\/\/www.energeticambiente.it\/labenergie\/wp-json\/wp\/v2\/pages\/2730\/revisions\/2921"}],"wp:attachment":[{"href":"https:\/\/www.energeticambiente.it\/labenergie\/wp-json\/wp\/v2\/media?parent=2730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}